{"id":31,"count":1,"description":"","link":"https:\/\/blog.residenceoliveto.it\/en\/tag\/museo-navale\/","name":"museo navale","slug":"museo-navale","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>museo navale Archivi - Residence Oliveto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.residenceoliveto.it\/tag\/museo-navale\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"museo navale Archivi - Residence Oliveto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.residenceoliveto.it\/tag\/museo-navale\/\",\"url\":\"https:\/\/blog.residenceoliveto.it\/tag\/museo-navale\/\",\"name\":\"museo navale Archivi - Residence Oliveto\",\"isPartOf\":{\"@id\":\"https:\/\/blog.residenceoliveto.it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.residenceoliveto.it\/tag\/museo-navale\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.residenceoliveto.it\/tag\/museo-navale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.residenceoliveto.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"museo navale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.residenceoliveto.it\/#website\",\"url\":\"https:\/\/blog.residenceoliveto.it\/\",\"name\":\"Residence Oliveto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.residenceoliveto.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"museo navale Archivi - Residence Oliveto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.residenceoliveto.it\/tag\/museo-navale\/","twitter_card":"summary_large_image","twitter_title":"museo navale Archivi - Residence Oliveto","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.residenceoliveto.it\/tag\/museo-navale\/","url":"https:\/\/blog.residenceoliveto.it\/tag\/museo-navale\/","name":"museo navale Archivi - Residence Oliveto","isPartOf":{"@id":"https:\/\/blog.residenceoliveto.it\/#website"},"breadcrumb":{"@id":"https:\/\/blog.residenceoliveto.it\/tag\/museo-navale\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.residenceoliveto.it\/tag\/museo-navale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.residenceoliveto.it\/"},{"@type":"ListItem","position":2,"name":"museo navale"}]},{"@type":"WebSite","@id":"https:\/\/blog.residenceoliveto.it\/#website","url":"https:\/\/blog.residenceoliveto.it\/","name":"Residence Oliveto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.residenceoliveto.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/blog.residenceoliveto.it\/en\/wp-json\/wp\/v2\/tags\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.residenceoliveto.it\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.residenceoliveto.it\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.residenceoliveto.it\/en\/wp-json\/wp\/v2\/posts?tags=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}